{"id":4085,"date":"2018-09-21T09:18:06","date_gmt":"2018-09-21T07:18:06","guid":{"rendered":"https:\/\/www.eltern-forum.at\/ratgeber-news\/?p=4085"},"modified":"2018-09-26T07:20:46","modified_gmt":"2018-09-26T05:20:46","slug":"babys-wunder-po-windeldermatitis","status":"publish","type":"post","link":"https:\/\/www.eltern-forum.at\/ratgeber-news\/babys-wunder-po-windeldermatitis\/","title":{"rendered":"Babys wunder Po \u2013 Windeldermatitis"},"content":{"rendered":"<p>Wenn der <strong>Windelbereich<\/strong> rund um den After und die Leisten des Babys ger\u00f6tet sind, sich schuppt oder n\u00e4sst, dann spricht man von einer <strong>Windeldermatitis<\/strong>.<\/p>\n<p>Die zarte Babyhaut ist durch den <em>Urin oder Kot<\/em> in Kombination mit der feuchten und warmen Luft der <a href=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/thema-wickeln-windeln-im-vergleich\/\">Windel<\/a> besch\u00e4digt worden. Gr\u00fcnde f\u00fcr eine Windeldermatitis k\u00f6nnen folgende sein.<\/p>\n<h2>Gr\u00fcnde f\u00fcr einen Wunden Po bei Babys<\/h2>\n<ul class=\"checklist\">\n<li>Durchfallerkrankungen,<\/li>\n<li>zu scharfer oder zu saurer Kot, oft als Folge einer Nahrungsumstellung oder bei <strong>Verdauungsschw\u00e4chen<\/strong><\/li>\n<li><strong>Urin<\/strong> ist zu hoch konzentriert, als Folge einer Erk\u00e4ltung<\/li>\n<li>bei gleichzeitiger Gabe von <strong>Medikamenten<\/strong>, z.B. Antibiotika<\/li>\n<li><strong>Empfindlichkeit<\/strong> gegen Windel-Material oder bestimmte Pflegeprodukte<\/li>\n<li>das Kind <strong>zahnt<\/strong>, was oft zu Hautausschl\u00e4gen f\u00fchrt.<\/li>\n<li><strong>Pilze oder Bakterien<\/strong>: Hier m\u00fcssen Eltern handeln und den Arzt aufsuchen. Zu erkennen ist ein Pilzbefall daran, dass es zu fl\u00e4chigen R\u00f6tungen und zu Kn\u00f6tchenbildung kommt. Eiterbl\u00e4schen und Pusteln hingegen sind Anzeichen f\u00fcr Bakterien.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-4086\" src=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/09\/baby-mit-windel.jpg\" alt=\"\" width=\"750\" height=\"525\" \/><\/p>\n<h2>Selbsthilfe bei wundem Baby-Po<\/h2>\n<p>Der <strong>Gang zum Kinderarzt<\/strong> kann bei den meisten Ursachen f\u00fcr einen wunden Po vermieden werden. Eltern k\u00f6nnen dem Kind selbst helfen, m\u00fcssen dabei aber einige Dinge beachten. Am wichtigsten ist es, dass die wunden Stellen trocken gehalten werden. Der Kinderpo sollte daher so oft es geht ohne Windel sein.<\/p>\n<p>Eltern sollten das Kind h\u00e4ufiger als sonst neu <a href=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/wickeln-wissenswertes-rund-um-babys-po\/\">wickeln<\/a>. So kann verhindert werden, dass sich die Feuchtigkeit durch den Urin mit der warmen Luft verbindet und so kann die Windeldermatitis nicht abheilen.<\/p>\n<p class=\"tipp\">Ein <strong>Tipp<\/strong> ist auch eine Windeleinlage aus Bouretteseide. Diese sollen die Feuchtigkeit von der Haut ableiten, sind weich auf der Haut und verhindern das Verkleben an den wunden stellen. Die Windeleinlagen gibt es sowohl in Apotheken, als auch im Internet.<\/p>\n<p>Die schon wunden Stellen auf Babys Popo m\u00fcssen auch behandelt werden. M\u00fctter, die das Kind stillen k\u00f6nnen Muttermilch mit einem weichen und sauberen Tuch auf den Po tupfen. Wer nicht stillt, kann sich auch mit Kamillentee oder Schwarztee behelfen. Sie haben die Eigenschaft, dass sie die Haut beruhigen und k\u00fchlen. Alternativ zu diesen Hausmitteln kann auch eine Zinksalbe benutzt werden, die es rezeptfrei in Apotheken und Drogerien zu kaufen.<\/p>\n<p><a href=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/das-stillen\/\">Stillende M\u00fctter<\/a> sollten w\u00e4hrend der Windeldermatitis auch auf ihre eigene Ern\u00e4hrung achten, damit Urin und Stuhl vom Baby nicht sauer werden und die schon gereizte Haut noch weiter reizen.\u00a0 So sollten weder N\u00fcsse noch Schokolade gegessen werden. Auf s\u00e4urehaltiges Obst und Gem\u00fcse sollte die Mutter genauso verzichten, wie auf Kuhmilch.<\/p>\n<h3><img decoding=\"async\" class=\"aligncenter size-full wp-image-4087\" src=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/09\/baby-po-windel.jpg\" alt=\"\" width=\"750\" height=\"525\" \/><\/h3>\n<h3>Der Windeldermatitis vorbeugen<\/h3>\n<p>Hautausschl\u00e4ge sind bei Kindern mit Windel nicht selten. Eltern k\u00f6nnen es nie so ganz verhindern, sie k\u00f6nnen aber darauf achten, dass sie nicht zu oft auftreten. So sollte immer auf eine ausreichende, aber nicht \u00fcbertriebene Hygiene geachtet werden. Eine neue Windel nach jedem Stuhlgang ist absolutes Muss, davor sollte die Haut des Kindes aber gr\u00fcndlich gereinigt und abgetrocknet werden. Zur Reinigung sollen Eltern nur klares Wasser benutzen.<\/p>\n<p>Wenn Pflegeprodukte notwendig sind, dann sollten sie immer frei von Zusatzstoffen sein.<\/p>\n<p>Bei der Ern\u00e4hrung sollte darauf geachtet werden, dass Obst und Gem\u00fcse nicht zu viel S\u00e4ure enth\u00e4lt. Grade bei Kindern, die oft an der Windeldermatitis leiden, sollten diese nur noch in Ma\u00dfen gegessen<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn der Windelbereich rund um den After und die Leisten des Babys ger\u00f6tet sind, sich schuppt oder n\u00e4sst, dann spricht man von einer Windeldermatitis&#8230;.<\/p>\n","protected":false},"author":3,"featured_media":4142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[27],"tags":[],"class_list":["post-4085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesundheit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Babys wunder Po \u2013 Windeldermatitis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/babys-wunder-po-windeldermatitis\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Babys wunder Po \u2013 Windeldermatitis\" \/>\n<meta property=\"og:description\" content=\"Wenn der Windelbereich rund um den After und die Leisten des Babys ger\u00f6tet sind, sich schuppt oder n\u00e4sst, dann spricht man von einer Windeldermatitis....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/babys-wunder-po-windeldermatitis\/\" \/>\n<meta property=\"og:site_name\" content=\"Eltern Ratgeber News\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-21T07:18:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-26T05:20:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/09\/baby-po-windel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lea Himmel\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lea Himmel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/babys-wunder-po-windeldermatitis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/babys-wunder-po-windeldermatitis\\\/\"},\"author\":{\"name\":\"Lea Himmel\",\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#\\\/schema\\\/person\\\/0aa87ae35513ed5ac527b597339d87aa\"},\"headline\":\"Babys wunder Po \u2013 Windeldermatitis\",\"datePublished\":\"2018-09-21T07:18:06+00:00\",\"dateModified\":\"2018-09-26T05:20:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/babys-wunder-po-windeldermatitis\\\/\"},\"wordCount\":542,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/babys-wunder-po-windeldermatitis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/baby-po-windel.jpg\",\"articleSection\":[\"Gesundheit\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/babys-wunder-po-windeldermatitis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/babys-wunder-po-windeldermatitis\\\/\",\"url\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/babys-wunder-po-windeldermatitis\\\/\",\"name\":\"Babys wunder Po \u2013 Windeldermatitis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/babys-wunder-po-windeldermatitis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/babys-wunder-po-windeldermatitis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/baby-po-windel.jpg\",\"datePublished\":\"2018-09-21T07:18:06+00:00\",\"dateModified\":\"2018-09-26T05:20:46+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/babys-wunder-po-windeldermatitis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/babys-wunder-po-windeldermatitis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/baby-po-windel.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/baby-po-windel.jpg\",\"width\":750,\"height\":525},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#website\",\"url\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/\",\"name\":\"Eltern Ratgeber News\",\"description\":\"ein Projekt von eltern-forum.at\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#organization\",\"name\":\"Eltern Ratgeber News\",\"url\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/eltern-forum-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/eltern-forum-logo.svg\",\"width\":350,\"height\":80,\"caption\":\"Eltern Ratgeber News\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#\\\/schema\\\/person\\\/0aa87ae35513ed5ac527b597339d87aa\",\"name\":\"Lea Himmel\",\"description\":\"Seit meiner ersten Schwangerschaft besch\u00e4ftige ich mich mit vielen Fragen rund ums Eltern-werden. Ich habe das eltern-forum.at im Jahr 2005 zum Informationsaustausch gegr\u00fcndet. Ich als zweifache Mami und meine Freundinnen und Freunde berichten hier \u00fcber Erfahrungen.\",\"url\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/author\\\/mediennetzwerk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Babys wunder Po \u2013 Windeldermatitis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eltern-forum.at\/ratgeber-news\/babys-wunder-po-windeldermatitis\/","og_locale":"de_DE","og_type":"article","og_title":"Babys wunder Po \u2013 Windeldermatitis","og_description":"Wenn der Windelbereich rund um den After und die Leisten des Babys ger\u00f6tet sind, sich schuppt oder n\u00e4sst, dann spricht man von einer Windeldermatitis....","og_url":"https:\/\/www.eltern-forum.at\/ratgeber-news\/babys-wunder-po-windeldermatitis\/","og_site_name":"Eltern Ratgeber News","article_published_time":"2018-09-21T07:18:06+00:00","article_modified_time":"2018-09-26T05:20:46+00:00","og_image":[{"width":750,"height":525,"url":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/09\/baby-po-windel.jpg","type":"image\/jpeg"}],"author":"Lea Himmel","twitter_misc":{"Verfasst von":"Lea Himmel","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/babys-wunder-po-windeldermatitis\/#article","isPartOf":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/babys-wunder-po-windeldermatitis\/"},"author":{"name":"Lea Himmel","@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#\/schema\/person\/0aa87ae35513ed5ac527b597339d87aa"},"headline":"Babys wunder Po \u2013 Windeldermatitis","datePublished":"2018-09-21T07:18:06+00:00","dateModified":"2018-09-26T05:20:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/babys-wunder-po-windeldermatitis\/"},"wordCount":542,"commentCount":0,"publisher":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#organization"},"image":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/babys-wunder-po-windeldermatitis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/09\/baby-po-windel.jpg","articleSection":["Gesundheit"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eltern-forum.at\/ratgeber-news\/babys-wunder-po-windeldermatitis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/babys-wunder-po-windeldermatitis\/","url":"https:\/\/www.eltern-forum.at\/ratgeber-news\/babys-wunder-po-windeldermatitis\/","name":"Babys wunder Po \u2013 Windeldermatitis","isPartOf":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/babys-wunder-po-windeldermatitis\/#primaryimage"},"image":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/babys-wunder-po-windeldermatitis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/09\/baby-po-windel.jpg","datePublished":"2018-09-21T07:18:06+00:00","dateModified":"2018-09-26T05:20:46+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eltern-forum.at\/ratgeber-news\/babys-wunder-po-windeldermatitis\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/babys-wunder-po-windeldermatitis\/#primaryimage","url":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/09\/baby-po-windel.jpg","contentUrl":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/09\/baby-po-windel.jpg","width":750,"height":525},{"@type":"WebSite","@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#website","url":"https:\/\/www.eltern-forum.at\/ratgeber-news\/","name":"Eltern Ratgeber News","description":"ein Projekt von eltern-forum.at","publisher":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eltern-forum.at\/ratgeber-news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#organization","name":"Eltern Ratgeber News","url":"https:\/\/www.eltern-forum.at\/ratgeber-news\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#\/schema\/logo\/image\/","url":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2022\/12\/eltern-forum-logo.svg","contentUrl":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2022\/12\/eltern-forum-logo.svg","width":350,"height":80,"caption":"Eltern Ratgeber News"},"image":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#\/schema\/person\/0aa87ae35513ed5ac527b597339d87aa","name":"Lea Himmel","description":"Seit meiner ersten Schwangerschaft besch\u00e4ftige ich mich mit vielen Fragen rund ums Eltern-werden. Ich habe das eltern-forum.at im Jahr 2005 zum Informationsaustausch gegr\u00fcndet. Ich als zweifache Mami und meine Freundinnen und Freunde berichten hier \u00fcber Erfahrungen.","url":"https:\/\/www.eltern-forum.at\/ratgeber-news\/author\/mediennetzwerk\/"}]}},"taxonomy_info":{"category":[{"value":27,"label":"Gesundheit"}]},"featured_image_src_large":["https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/09\/baby-po-windel.jpg",750,525,false],"author_info":{"display_name":"Lea Himmel","author_link":"https:\/\/www.eltern-forum.at\/ratgeber-news\/author\/mediennetzwerk\/"},"comment_info":0,"category_info":[{"term_id":27,"name":"Gesundheit","slug":"gesundheit","term_group":0,"term_taxonomy_id":27,"taxonomy":"category","description":"Gesundheit ist das Wichtigste, was wir haben. Und doch besch\u00e4ftigt sie uns oft erst, wenn es zu sp\u00e4t ist. Auf diesem Blog m\u00f6chte ich euch helfen, euren Alltag ges\u00fcnder und gl\u00fccklicher zu gestalten. Ihr findet hier Tipps und Tricks rund um die Themen Gesundheit, Ern\u00e4hrung und Bewegung f\u00fcr die ganze Familie. Also liebe Eltern, nehmt euch die Zeit f\u00fcr euer Wohlergehen \u2013 es lohnt sich!\r\n\r\n\r\n","parent":0,"count":48,"filter":"raw","cat_ID":27,"category_count":48,"category_description":"Gesundheit ist das Wichtigste, was wir haben. Und doch besch\u00e4ftigt sie uns oft erst, wenn es zu sp\u00e4t ist. Auf diesem Blog m\u00f6chte ich euch helfen, euren Alltag ges\u00fcnder und gl\u00fccklicher zu gestalten. Ihr findet hier Tipps und Tricks rund um die Themen Gesundheit, Ern\u00e4hrung und Bewegung f\u00fcr die ganze Familie. Also liebe Eltern, nehmt euch die Zeit f\u00fcr euer Wohlergehen \u2013 es lohnt sich!\r\n\r\n\r\n","cat_name":"Gesundheit","category_nicename":"gesundheit","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/posts\/4085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/comments?post=4085"}],"version-history":[{"count":0,"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/posts\/4085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/media\/4142"}],"wp:attachment":[{"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/media?parent=4085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/categories?post=4085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/tags?post=4085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}