{"id":4219,"date":"2018-11-02T10:43:05","date_gmt":"2018-11-02T08:43:05","guid":{"rendered":"https:\/\/www.eltern-forum.at\/ratgeber-news\/?p=4219"},"modified":"2018-11-02T10:43:05","modified_gmt":"2018-11-02T08:43:05","slug":"milchschorf","status":"publish","type":"post","link":"https:\/\/www.eltern-forum.at\/ratgeber-news\/milchschorf\/","title":{"rendered":"Milchschorf- was ist das?"},"content":{"rendered":"<p>Milchschorf ist eine relativ h\u00e4ufig auftretende <strong>Hautver\u00e4nderung<\/strong>, die zumeist bei <a href=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/baby-und-kinderratgeber\/\">Babys und Kleinkindern<\/a> auftritt. Auf der Kopfhaut und manchmal auch im Gesicht bilden sich gelblich wei\u00dfe, harte Schuppen. Die Haut darunter ist ger\u00f6tet und n\u00e4sst, oftmals leidet der kleine Patient unter Juckreiz.<\/p>\n<p><strong>Milchschorf<\/strong> tritt im Rahmen eines sogenannten atopischen Ekzems auf und ist daher als Erstmanifestation einer <strong>Neurodermatitis<\/strong> zu verstehen. Seltener entsteht Milchschorf auch auf anderen K\u00f6rperstellen wie z.B. in den Arm- oder Kniebeugen, auf den Hand- oder Fu\u00dfr\u00fccken sowie auf Gesicht und Hals.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-4225\" src=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/11\/milchschoft.jpg\" alt=\"\" width=\"750\" height=\"522\" srcset=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/11\/milchschoft.jpg 750w, https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/11\/milchschoft-300x209.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<h2>Was ist Milchschorf?<\/h2>\n<p>F\u00e4lschlicherweise wird Milchschorf von Laien und sogar Fachleuten manchmal mit einer als <strong>Gneis<\/strong> (<em>seborrhoisches Ekzem<\/em>) bekannten Schuppung der Kopfhaut des Kindes verwechselt. Gneis ist als Folge der hormonellen Umstellung im Babyalter v\u00f6llig unproblematisch und verschwindet in der Regel bald von selbst wieder.<\/p>\n<p>Die gelblichen, recht gro\u00dfen Hautschuppen sind im Gegensatz zu der Abschuppung bei Milchschorf weich und fettig. Sie stellen lediglich ein kosmetisches Problem dar und beeintr\u00e4chtigen das Wohlbefinden des Kindes \u00fcberhaupt nicht. Die folgende Aufstellung verdeutlicht die Unterschiede zwischen Milchschorf und Gneis und hilft bei der Unterscheidung und Erkennung der Hautver\u00e4nderung:<\/p>\n<h2>Wie unterscheidet sich Milchschorf von Gneis?<\/h2>\n<h3>Echter Milchschorf \/ atopisches Ekzem<\/h3>\n<ul class=\"checklist\">\n<li>beginnt meist ab dem dritten Lebensmonat<\/li>\n<li>besteht \u00fcber einen l\u00e4ngeren Zeitraum bis zu zwei Jahre<\/li>\n<li>zeigt sich durch R\u00f6tung und Bl\u00e4schenbildung, anschlie\u00dfende Verkrustung der Haut und Bildung harter Schuppen<\/li>\n<li>bewirkt starken Juckreiz<\/li>\n<li>kann in eine chronische Neurodermitis \u00fcbergehen<\/li>\n<\/ul>\n<h3>Gneis\/ seborrhoisches Ekzem<\/h3>\n<ul class=\"checklist\">\n<li>erscheint im ersten Lebensmonat<\/li>\n<li>heilt, bis auf einige Ausnahmen, zumeist im ersten Lebensjahr ab<\/li>\n<li>bildet weiche, gelbliche, fettige Schuppenplatten<\/li>\n<li>juckt nicht<\/li>\n<li>wird nicht chronisch und heilt ohne Folgen aus<\/li>\n<\/ul>\n<h2>Wie kann Milchschorf behandelt werden?<\/h2>\n<p>W\u00e4hrend bei Gneis durch Ein\u00f6len und sanftes Durchb\u00fcrsten der Haare eine Abl\u00f6sung der Schuppen erreicht werden kann, sollte bei echtem Milchschorf stets ein Arzt konsultiert werden.<\/p>\n<p>Neben Juckreiz bek\u00e4mpfenden Mitteln kann er die geeignete Therapie f\u00fcr den kleinen Patienten anordnen. Die <strong>schuppende Haut<\/strong> sollte weder bei Gneis noch bei Milchschorf abgekratzt werden, sonst entstehen kleine Wunden, welche im schlimmsten Falle durch den Eintritt von Bakterien Entz\u00fcndungen zur Folge h\u00e4tten. In diesem Zusammenhang sollte auch darauf geachtet werden, dass die Fingern\u00e4gel des Kindes immer gut gek\u00fcrzt sind.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-4226\" src=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/11\/baby-fuss-oelen.jpg\" alt=\"\" width=\"750\" height=\"525\" srcset=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/11\/baby-fuss-oelen.jpg 750w, https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/11\/baby-fuss-oelen-300x210.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Wenn n\u00f6tig, sollte es \u00fcber Nacht F\u00e4ustlinge tragen. So l\u00e4sst sich sch\u00e4dliches Kratzen weitestgehend vermeiden. Anstelle von F\u00e4ustlingen k\u00f6nnen auch Babys\u00f6ckchen aus Baumwolle \u00fcber die H\u00e4nde des S\u00e4uglings gezogen werden.<\/p>\n<p class=\"info\">Sollte der Juckreiz allzu stark sein, hilft das sanfte Ein\u00f6len mit einem <strong>unparf\u00fcmierten Baby\u00f6l, Kokos\u00f6l oder Oliven\u00f6l<\/strong>. Das \u00d6l sollte \u00fcber mehrere Stunden einziehen, die abgel\u00f6sten Schuppen k\u00f6nnen dann vorsichtig ausgek\u00e4mmt und ausgezupft werden. Ein Auftragen des \u00d6ls vor dem Schlafengehen bietet sich an, so kann es \u00fcber Nacht einwirken. Die K\u00fchlung der Haut mit einem feuchten Tuch oder einem m\u00e4\u00dfig kalten K\u00fchlpack lindert den Juckreiz rasch. Das K\u00fchlpack sollte nicht eiskalt sein, es reicht, wenn es f\u00fcr einige Zeit im K\u00fchlschrank gelegen hat.<\/p>\n<h2>Wie entsteht Milchschorf?<\/h2>\n<p>Der Entstehung von Milchschorf liegen erbliche Faktoren zugrunde, es gibt daher keine M\u00f6glichkeit, vorzubeugen. Sind Mutter oder Vater <strong>Neurodermitiker<\/strong>, besteht die Wahrscheinlichkeit, dass das Kind ebenfalls daran erkranken wird.<\/p>\n<p>Ein Ausl\u00f6sen des Ekzems kann durch verschiedenste Faktoren erfolgen. Bestimmte Inhaltstoffe von Waschmitteln oder Hautpflege, Umwelteinfl\u00fcsse, Nahrungsmittel, Infektionen oder auch Ver\u00e4nderungen im Umfeld k\u00f6nnen eine Rolle spielen. Eine Ursache herauszufinden, ist mit viel M\u00fche verbunden und erfolgt meist durch das Ausschlussverfahren, bei welchem durch Weglassen verschiedener m\u00f6glicher Ausl\u00f6ser eine Ver\u00e4nderung angestrebt wird.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-4228\" src=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/11\/baby-anziehen.jpg\" alt=\"\" width=\"750\" height=\"525\" srcset=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/11\/baby-anziehen.jpg 750w, https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/11\/baby-anziehen-300x210.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Das Tragen von Kleidung aus unbehandelter Baumwolle, welche vor dem Anziehen gewaschen wurde, ist hilfreich. Auch Kleidung mit G\u00fctesiegel, bestehend aus Baumwolle biologischer Herkunft, kann durch Lagerung und Transport Pilzsporen und andere Ausl\u00f6ser beherbergen. Waschmittel sollte nach hautschonenden Aspekten ausgew\u00e4hlt werden. Pflegemittel f\u00fcr Babys und Kleinkinder riechen immer sehr angenehm, trotzdem ist es im Falle von Milchschorf besser, zu einer Pflegeserie ohne Duft- und Konservierungsstoffe zu wechseln.<\/p>\n<p>Es ist zwar noch nicht wissenschaftlich bewiesen, aber langes Stillen soll sich positiv auf den Verlauf eines atopischen Ekzems auswirken. Welche Nahrungsmittel zudem gute oder schlechte Auswirkungen haben, l\u00e4sst sich durch das gezielte Weglassen herausfinden. Der Kinderarzt oder die Hebamme hat diesbez\u00fcglich fachkundige, fundierte Ratschl\u00e4ge parat.<\/p>\n<h2>Deutet der Name Milchschorf auf eine Unvertr\u00e4glichkeit von Milchprodukten hin?<\/h2>\n<p>Der Name Milchschorf l\u00e4sst vermuten, dass die Hautver\u00e4nderungen durch eine Unvertr\u00e4glichkeit von Milch und Milchprodukten ausgel\u00f6st werden. Der Ursprung dieser Bezeichnung liegt aber ganz woanders und r\u00fchrt daher, dass die gelben, fl\u00e4chigen Schuppen auf der Haut an das Aussehen von verbrannter, verkrusteter Milch erinnern. Die Bezeichnung Milchschorf f\u00fchrt daher h\u00e4ufig zu Fehlinterpretationen.<\/p>\n<h2>Was tun bei Milchschorf im Gesicht?<\/h2>\n<p>Manchmal zieht sich der Milchschorf bis in das Gesicht hinein. \u00dcblicherweise tritt die Hautver\u00e4nderung dann im Bereich der Stirn auf, vom Haaransatz bis zu den Augenbrauen. Auch die Wangen k\u00f6nnen betroffen sein. Es bilden sich R\u00f6tungen und kleine, n\u00e4ssende Bl\u00e4schen, die in der Folge verkrusten und eine gelblich wei\u00dfe, schuppige Schicht hinterlassen. Mitunter treten Entz\u00fcndungen auf. Wie auch bei Milchschorf auf dem Kopf sollte unbedingt vermieden werden, dass das Kind sich wegen des starken Juckreizes kratzt. Entz\u00fcndungen und vielleicht sogar Narbenbildung k\u00f6nnen die Folge von aufgekratztem Milchschorf sein. Das K\u00fchlen der betroffenen Stellen ist auch hier hilfreich.<\/p>\n<p class=\"info\">Der Kinderarzt kann nach erfolgter Diagnose die beste Therapie gegen Milchschorf empfehlen. Sollten die befallenen Stellen nicht entz\u00fcndet sein, kann durch das Betupfen mit \u00d6l oder einem speziellen Pflegeprodukt (<em>Auskunft dar\u00fcber kann der Apotheker geben<\/em>) eine Linderung erzielt werden.<\/p>\n<h2>Milchschorf im Erwachsenenalter<\/h2>\n<p>Ein erstmaliges Auftreten der Krankheit im Erwachsenenalter ist selten, kommt aber vor. Die Symptome sind identisch mit denen beim Kleinkind. Schuppige Krusten auf der Kopfhaut, unter denen die Haut ger\u00f6tet und entz\u00fcndet ist, Schuppen und Juckreiz deuten auf Milchschorf hin.<\/p>\n<p>Zur sicheren Abgrenzung zu anderen Krankheiten wie z.B. Schuppenflechte oder dem seborrhoischen Ekzem ist ein Arztbesuch unabdingbar. Die Ursachen f\u00fcr eine Erkrankung im Erwachsenenalter \u00e4hneln denen im Kindesalter. Vererbung, \u00fcberm\u00e4\u00dfige Talgproduktion oder ein Pilz k\u00f6nnen die Ausl\u00f6ser sein. Das Auftreten der Erkrankung erfolgt h\u00e4ufig in Sch\u00fcben. Zeitweise treten die Symptome st\u00e4rker auf, dann folgt eine symptomfreie Zeit. Man vermutet, dass der Stresslevel hier eine gro\u00dfe Rolle spielt.<\/p>\n<p>Neben der Verwendung der vom Arzt empfohlenen Medikamente helfen frische Luft und Sonnenlicht beim Abheilen. Reine \u00d6le sowie spezielle Lotionen aus der Apotheke beschleunigen den Heilungsprozess. Stark duftende, chemische Pflege- und Stylingprodukte sollten vermieden werden. Es ist ratsam, Stress zu reduzieren, damit die entz\u00fcndete Haut zur Ruhe kommen kann. Auch wenn es schwer f\u00e4llt: Das Aufkratzen der Verkrustungen sollte vermieden werden. Sonst drohen Entz\u00fcndungen und Vernarbungen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Milchschorf ist eine relativ h\u00e4ufig auftretende Hautver\u00e4nderung, die zumeist bei Babys und Kleinkindern auftritt. Auf der Kopfhaut und manchmal auch im Gesicht bilden sich&#8230;<\/p>\n","protected":false},"author":3,"featured_media":4225,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[27],"tags":[],"class_list":["post-4219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesundheit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Milchschorf- was ist das?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/milchschorf\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Milchschorf- was ist das?\" \/>\n<meta property=\"og:description\" content=\"Milchschorf ist eine relativ h\u00e4ufig auftretende Hautver\u00e4nderung, die zumeist bei Babys und Kleinkindern auftritt. Auf der Kopfhaut und manchmal auch im Gesicht bilden sich...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/milchschorf\/\" \/>\n<meta property=\"og:site_name\" content=\"Eltern Ratgeber News\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-02T08:43:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/11\/milchschoft.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"522\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lea Himmel\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lea Himmel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/milchschorf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/milchschorf\\\/\"},\"author\":{\"name\":\"Lea Himmel\",\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#\\\/schema\\\/person\\\/0aa87ae35513ed5ac527b597339d87aa\"},\"headline\":\"Milchschorf- was ist das?\",\"datePublished\":\"2018-11-02T08:43:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/milchschorf\\\/\"},\"wordCount\":1147,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/milchschorf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/milchschoft.jpg\",\"articleSection\":[\"Gesundheit\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/milchschorf\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/milchschorf\\\/\",\"url\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/milchschorf\\\/\",\"name\":\"Milchschorf- was ist das?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/milchschorf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/milchschorf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/milchschoft.jpg\",\"datePublished\":\"2018-11-02T08:43:05+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/milchschorf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/milchschorf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/milchschoft.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/milchschoft.jpg\",\"width\":750,\"height\":522},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#website\",\"url\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/\",\"name\":\"Eltern Ratgeber News\",\"description\":\"ein Projekt von eltern-forum.at\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#organization\",\"name\":\"Eltern Ratgeber News\",\"url\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/eltern-forum-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/eltern-forum-logo.svg\",\"width\":350,\"height\":80,\"caption\":\"Eltern Ratgeber News\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/#\\\/schema\\\/person\\\/0aa87ae35513ed5ac527b597339d87aa\",\"name\":\"Lea Himmel\",\"description\":\"Seit meiner ersten Schwangerschaft besch\u00e4ftige ich mich mit vielen Fragen rund ums Eltern-werden. Ich habe das eltern-forum.at im Jahr 2005 zum Informationsaustausch gegr\u00fcndet. Ich als zweifache Mami und meine Freundinnen und Freunde berichten hier \u00fcber Erfahrungen.\",\"url\":\"https:\\\/\\\/www.eltern-forum.at\\\/ratgeber-news\\\/author\\\/mediennetzwerk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Milchschorf- was ist das?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eltern-forum.at\/ratgeber-news\/milchschorf\/","og_locale":"de_DE","og_type":"article","og_title":"Milchschorf- was ist das?","og_description":"Milchschorf ist eine relativ h\u00e4ufig auftretende Hautver\u00e4nderung, die zumeist bei Babys und Kleinkindern auftritt. Auf der Kopfhaut und manchmal auch im Gesicht bilden sich...","og_url":"https:\/\/www.eltern-forum.at\/ratgeber-news\/milchschorf\/","og_site_name":"Eltern Ratgeber News","article_published_time":"2018-11-02T08:43:05+00:00","og_image":[{"width":750,"height":522,"url":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/11\/milchschoft.jpg","type":"image\/jpeg"}],"author":"Lea Himmel","twitter_misc":{"Verfasst von":"Lea Himmel","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/milchschorf\/#article","isPartOf":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/milchschorf\/"},"author":{"name":"Lea Himmel","@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#\/schema\/person\/0aa87ae35513ed5ac527b597339d87aa"},"headline":"Milchschorf- was ist das?","datePublished":"2018-11-02T08:43:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/milchschorf\/"},"wordCount":1147,"commentCount":0,"publisher":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#organization"},"image":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/milchschorf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/11\/milchschoft.jpg","articleSection":["Gesundheit"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eltern-forum.at\/ratgeber-news\/milchschorf\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/milchschorf\/","url":"https:\/\/www.eltern-forum.at\/ratgeber-news\/milchschorf\/","name":"Milchschorf- was ist das?","isPartOf":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/milchschorf\/#primaryimage"},"image":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/milchschorf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/11\/milchschoft.jpg","datePublished":"2018-11-02T08:43:05+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eltern-forum.at\/ratgeber-news\/milchschorf\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/milchschorf\/#primaryimage","url":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/11\/milchschoft.jpg","contentUrl":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/11\/milchschoft.jpg","width":750,"height":522},{"@type":"WebSite","@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#website","url":"https:\/\/www.eltern-forum.at\/ratgeber-news\/","name":"Eltern Ratgeber News","description":"ein Projekt von eltern-forum.at","publisher":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eltern-forum.at\/ratgeber-news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#organization","name":"Eltern Ratgeber News","url":"https:\/\/www.eltern-forum.at\/ratgeber-news\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#\/schema\/logo\/image\/","url":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2022\/12\/eltern-forum-logo.svg","contentUrl":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2022\/12\/eltern-forum-logo.svg","width":350,"height":80,"caption":"Eltern Ratgeber News"},"image":{"@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eltern-forum.at\/ratgeber-news\/#\/schema\/person\/0aa87ae35513ed5ac527b597339d87aa","name":"Lea Himmel","description":"Seit meiner ersten Schwangerschaft besch\u00e4ftige ich mich mit vielen Fragen rund ums Eltern-werden. Ich habe das eltern-forum.at im Jahr 2005 zum Informationsaustausch gegr\u00fcndet. Ich als zweifache Mami und meine Freundinnen und Freunde berichten hier \u00fcber Erfahrungen.","url":"https:\/\/www.eltern-forum.at\/ratgeber-news\/author\/mediennetzwerk\/"}]}},"taxonomy_info":{"category":[{"value":27,"label":"Gesundheit"}]},"featured_image_src_large":["https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-content\/uploads\/2018\/11\/milchschoft.jpg",750,522,false],"author_info":{"display_name":"Lea Himmel","author_link":"https:\/\/www.eltern-forum.at\/ratgeber-news\/author\/mediennetzwerk\/"},"comment_info":0,"category_info":[{"term_id":27,"name":"Gesundheit","slug":"gesundheit","term_group":0,"term_taxonomy_id":27,"taxonomy":"category","description":"Gesundheit ist das Wichtigste, was wir haben. Und doch besch\u00e4ftigt sie uns oft erst, wenn es zu sp\u00e4t ist. Auf diesem Blog m\u00f6chte ich euch helfen, euren Alltag ges\u00fcnder und gl\u00fccklicher zu gestalten. Ihr findet hier Tipps und Tricks rund um die Themen Gesundheit, Ern\u00e4hrung und Bewegung f\u00fcr die ganze Familie. Also liebe Eltern, nehmt euch die Zeit f\u00fcr euer Wohlergehen \u2013 es lohnt sich!\r\n\r\n\r\n","parent":0,"count":47,"filter":"raw","cat_ID":27,"category_count":47,"category_description":"Gesundheit ist das Wichtigste, was wir haben. Und doch besch\u00e4ftigt sie uns oft erst, wenn es zu sp\u00e4t ist. Auf diesem Blog m\u00f6chte ich euch helfen, euren Alltag ges\u00fcnder und gl\u00fccklicher zu gestalten. Ihr findet hier Tipps und Tricks rund um die Themen Gesundheit, Ern\u00e4hrung und Bewegung f\u00fcr die ganze Familie. Also liebe Eltern, nehmt euch die Zeit f\u00fcr euer Wohlergehen \u2013 es lohnt sich!\r\n\r\n\r\n","cat_name":"Gesundheit","category_nicename":"gesundheit","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/posts\/4219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/comments?post=4219"}],"version-history":[{"count":0,"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/posts\/4219\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/media\/4225"}],"wp:attachment":[{"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/media?parent=4219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/categories?post=4219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eltern-forum.at\/ratgeber-news\/wp-json\/wp\/v2\/tags?post=4219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}